{"id":33761,"date":"2025-09-05T08:21:22","date_gmt":"2025-09-05T08:21:22","guid":{"rendered":"https:\/\/goolets.net\/yacht-rentals\/maya\/"},"modified":"2025-09-05T08:21:22","modified_gmt":"2025-09-05T08:21:22","slug":"maya","status":"publish","type":"yachts","link":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/","title":{"rendered":"Maya"},"excerpt":{"rendered":"","protected":false},"featured_media":33780,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"yacht_category":[],"class_list":["post-33761","yachts","type-yachts","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Yacht Maya 2026 Update - Goolets<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maya\" \/>\n<meta property=\"og:url\" content=\"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/\" \/>\n<meta property=\"og:site_name\" content=\"Goolets\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GooletsCruising\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/goolets.da.enki.si\/wp-content\/uploads\/2025\/09\/MAYA-Featured-image-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@gooletscruising\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/\",\"url\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/\",\"name\":\"Yacht Maya 2026 Update - Goolets\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/goolets.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/MAYA-Featured-image-scaled.avif\",\"datePublished\":\"2025-09-05T08:21:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#primaryimage\",\"url\":\"https:\\\/\\\/goolets.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/MAYA-Featured-image-scaled.avif\",\"contentUrl\":\"https:\\\/\\\/goolets.net\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/MAYA-Featured-image-scaled.avif\",\"width\":1920,\"height\":1280,\"caption\":\"Imagen destacada del MAYA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/goolets.net\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yachts\",\"item\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Maya\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/goolets.net\\\/es\\\/\",\"name\":\"Goolets\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/goolets.net\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":[\"Organization\",\"Place\",\"TravelAgency\"],\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/#organization\",\"name\":\"Goolets\",\"alternateName\":\"Goolets yacht charter company\",\"url\":\"https:\\\/\\\/goolets.net\\\/es\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#local-main-organization-logo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GooletsCruising\\\/\",\"https:\\\/\\\/x.com\\\/gooletscruising\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCJi8ZtNRy07_IEaEew1-xgw\",\"https:\\\/\\\/www.instagram.com\\\/goolets\\\/\"],\"foundingDate\":\"2005-06-01\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"11\",\"maxValue\":\"50\"},\"address\":{\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#local-main-place-address\"},\"telephone\":[\"+38616208891\",\"+16463812043\"],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}],\"email\":\"charter@goolets.net\",\"vatID\":\"SI54963516\",\"globalLocationNumber\":\"+38616208891\"},{\"@type\":\"PostalAddress\",\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#local-main-place-address\",\"streetAddress\":\"Taborska cesta 38D\",\"addressLocality\":\"Grosuplje\",\"postalCode\":\"1290\",\"addressCountry\":\"SI\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/goolets.net\\\/es\\\/alquiler-de-yates\\\/maya\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/goolets.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/goolets-logo.svg\",\"contentUrl\":\"https:\\\/\\\/goolets.net\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/goolets-logo.svg\",\"width\":56,\"height\":57,\"caption\":\"Goolets\"}]}<\/script>\n<meta name=\"geo.placename\" content=\"Grosuplje\" \/>\n<meta name=\"geo.region\" content=\"Eslovenia\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yacht Maya 2026 Update - Goolets","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/","og_locale":"es_ES","og_type":"article","og_title":"Maya","og_url":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/","og_site_name":"Goolets","article_publisher":"https:\/\/www.facebook.com\/GooletsCruising\/","og_image":[{"width":2560,"height":1707,"url":"https:\/\/goolets.da.enki.si\/wp-content\/uploads\/2025\/09\/MAYA-Featured-image-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@gooletscruising","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/","url":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/","name":"Yacht Maya 2026 Update - Goolets","isPartOf":{"@id":"https:\/\/goolets.net\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#primaryimage"},"image":{"@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#primaryimage"},"thumbnailUrl":"https:\/\/goolets.net\/wp-content\/uploads\/2025\/09\/MAYA-Featured-image-scaled.avif","datePublished":"2025-09-05T08:21:22+00:00","breadcrumb":{"@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#primaryimage","url":"https:\/\/goolets.net\/wp-content\/uploads\/2025\/09\/MAYA-Featured-image-scaled.avif","contentUrl":"https:\/\/goolets.net\/wp-content\/uploads\/2025\/09\/MAYA-Featured-image-scaled.avif","width":1920,"height":1280,"caption":"Imagen destacada del MAYA"},{"@type":"BreadcrumbList","@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/goolets.net\/es\/"},{"@type":"ListItem","position":2,"name":"Yachts","item":"https:\/\/goolets.net\/es\/alquiler-de-yates\/"},{"@type":"ListItem","position":3,"name":"Maya"}]},{"@type":"WebSite","@id":"https:\/\/goolets.net\/es\/#website","url":"https:\/\/goolets.net\/es\/","name":"Goolets","description":"","publisher":{"@id":"https:\/\/goolets.net\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/goolets.net\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":["Organization","Place","TravelAgency"],"@id":"https:\/\/goolets.net\/es\/#organization","name":"Goolets","alternateName":"Goolets yacht charter company","url":"https:\/\/goolets.net\/es\/","logo":{"@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#local-main-organization-logo"},"image":{"@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#local-main-organization-logo"},"sameAs":["https:\/\/www.facebook.com\/GooletsCruising\/","https:\/\/x.com\/gooletscruising","https:\/\/www.youtube.com\/channel\/UCJi8ZtNRy07_IEaEew1-xgw","https:\/\/www.instagram.com\/goolets\/"],"foundingDate":"2005-06-01","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"11","maxValue":"50"},"address":{"@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#local-main-place-address"},"telephone":["+38616208891","+16463812043"],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}],"email":"charter@goolets.net","vatID":"SI54963516","globalLocationNumber":"+38616208891"},{"@type":"PostalAddress","@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#local-main-place-address","streetAddress":"Taborska cesta 38D","addressLocality":"Grosuplje","postalCode":"1290","addressCountry":"SI"},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/goolets.net\/es\/alquiler-de-yates\/maya\/#local-main-organization-logo","url":"https:\/\/goolets.net\/wp-content\/uploads\/2025\/07\/goolets-logo.svg","contentUrl":"https:\/\/goolets.net\/wp-content\/uploads\/2025\/07\/goolets-logo.svg","width":56,"height":57,"caption":"Goolets"}]},"geo.placename":"Grosuplje","geo.region":"Eslovenia"},"_links":{"self":[{"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/yachts\/33761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/yachts"}],"about":[{"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/types\/yachts"}],"version-history":[{"count":0,"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/yachts\/33761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/media\/33780"}],"wp:attachment":[{"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/media?parent=33761"}],"wp:term":[{"taxonomy":"yacht_category","embeddable":true,"href":"https:\/\/goolets.net\/es\/wp-json\/wp\/v2\/yacht_category?post=33761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}